{"id":7416,"date":"2023-11-15T14:06:49","date_gmt":"2023-11-15T19:06:49","guid":{"rendered":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/?p=7416"},"modified":"2023-11-15T14:06:49","modified_gmt":"2023-11-15T19:06:49","slug":"estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre","status":"publish","type":"post","link":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/","title":{"rendered":"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre"},"content":{"rendered":"<p>Durante los primeros 10 meses de 2023,\u00a0<strong>M\u00e9xico export\u00f3 2 millones 737,262 autos<\/strong>\u00a0al extranjero, lo que representa un incremento anual de 14.5%; de dicha cifra, el 77% de las unidades se enviaron a Estados Unidos, lo que se traduce en que el pa\u00eds vecino del norte lidera como\u00a0<b>principal destino de exportaci\u00f3n<\/b>\u00a0de veh\u00edculos.<\/p>\n<p><b>M\u00e9xico envi\u00f3 2 millones 115,075 autos a Estados Unidos\u00a0<\/b>de enero a octubre de este a\u00f1o, cifra que representa un crecimiento de 14.4% en su comparaci\u00f3n anual. Por segmento, 1 mill\u00f3n 769,969 corresponden a camiones ligeros y los 345,106 restantes pertenecen a veh\u00edculos, de acuerdo con datos del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi).<\/p>\n<p>Despu\u00e9s de Estados Unidos,\u00a0<strong>Canad\u00e1 es el segundo destino de exportaci\u00f3n de autos<\/strong>, seguido de Alemania, Brasil y Colombia.<\/p>\n<h2 id=\"autos-exportados-durante-los-primeros-10-meses\"><b>Autos exportados durante los primeros 10 meses<\/b><\/h2>\n<p>Dentro de las\u00a0<b>marcas que lideran en la exportaci\u00f3n de veh\u00edculos a Estados Unidos\u00a0<\/b>de enero a octubre se encuentran Toyota, General Motors (GM), Chrysler, Ford y KIA, con un modelo espec\u00edfico que supera las 221,000 unidades en el caso de Toyota.<\/p>\n<p>De acuerdo con el Registro Administrativo de la Industria Automotriz de Veh\u00edculos Ligeros (RAIAVL) del Inegi, estos fueron los\u00a0<b>modelos m\u00e1s exportados a Estados Unidos\u00a0<\/b>durante los primeros 10 meses de 2023 y la cantidad de unidades enviadas:<\/p>\n<ol>\n<li>Tacoma (Toyota): 221,946<\/li>\n<li>Equinox SUV (GM): 187,934<\/li>\n<li>RAM 2500 (Chrysler): 150,984<\/li>\n<li>Bronco Sport (Ford): 128,558<\/li>\n<li>Forte (KIA): 110,912<\/li>\n<\/ol>\n<p>En el caso de\u00a0<strong>Canad\u00e1, el segundo destino principal de exportaci\u00f3n de autos<\/strong>, lider\u00f3 la marca Chrysler, seguida de Volkswagen (VW), Toyota y GM.<\/p>\n<ol>\n<li>RAM 2500 (Chrysler): 21,676 unidades.<\/li>\n<li>Taos (VW): 16,706 unidades.<\/li>\n<li>Tiguan (VW): 15,355 unidades.<\/li>\n<li>Tacoma (Toyota): 13,856 unidades.<\/li>\n<li>Terrain SUV (GM): 14,689 unidades.<\/li>\n<\/ol>\n<h2 id=\"octubre-mes-record-para-la-exportacion\"><b>Octubre, mes r\u00e9cord para la exportaci\u00f3n\u00a0<\/b><\/h2>\n<p>Octubre fue un mes r\u00e9cord para un mes de octubre en la\u00a0<b>exportaci\u00f3n de veh\u00edculos al extranjero<\/b>, al enviarse 316,421 unidades, lo que represent\u00f3 la cifra m\u00e1s alta desde 2005, a\u00f1o en que el Inegi comenz\u00f3 a recolectar la informaci\u00f3n del RAIAVL.<\/p>\n<p>Esta cifra tambi\u00e9n mostr\u00f3 un crecimiento de 18.1% en comparaci\u00f3n con octubre de 2022, mientras que respecto al mes inmediato anterior,\u00a0<b>la exportaci\u00f3n de veh\u00edculos report\u00f3 un incremento de 5%<\/b>.<\/p>\n<blockquote><p><q>Octubre representa el tercer mes consecutivo de 2023 en el que exportamos por arriba de los niveles prepandemia de 2019, adem\u00e1s es el mejor mes de exportaciones desde 2005, cuando empez\u00f3 a recolectarse el registro del Inegi, lo que significa que estamos por muy buena ruta en t\u00e9rminos de exportaci\u00f3n<\/q><\/p>\n<p><cite>dijo en conferencia Odracir Barquera, director de la Asociaci\u00f3n Mexicana de la Industria Automotriz (AMIA<\/cite><\/p><\/blockquote>\n<p>Publicado originalmente por:\u00a0<a href=\"https:\/\/elceo.com\/negocios\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/\">https:\/\/elceo.com\/negocios\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los primeros 10 meses de 2023,\u00a0M\u00e9xico export\u00f3 2 millones 737,262 autos\u00a0al extranjero, lo que representa un incremento anual de 14.5%; de dicha cifra, el 77% de las unidades se enviaron a Estados Unidos, lo que se traduce en que el pa\u00eds vecino del norte lidera como\u00a0principal destino de exportaci\u00f3n\u00a0de veh\u00edculos. M\u00e9xico envi\u00f3 2 millones [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7417,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-7416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre - Blog | GPI NEWS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre - Blog | GPI NEWS\" \/>\n<meta property=\"og:description\" content=\"Durante los primeros 10 meses de 2023,\u00a0M\u00e9xico export\u00f3 2 millones 737,262 autos\u00a0al extranjero, lo que representa un incremento anual de 14.5%; de dicha cifra, el 77% de las unidades se enviaron a Estados Unidos, lo que se traduce en que el pa\u00eds vecino del norte lidera como\u00a0principal destino de exportaci\u00f3n\u00a0de veh\u00edculos. M\u00e9xico envi\u00f3 2 millones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog | GPI NEWS\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-15T19:06:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GPI NEWS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GPI NEWS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/\",\"url\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/\",\"name\":\"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre - Blog | GPI NEWS\",\"isPartOf\":{\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg\",\"datePublished\":\"2023-11-15T19:06:49+00:00\",\"author\":{\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#\/schema\/person\/f4851bb8a48c32d7fba5285caf4ef1c4\"},\"breadcrumb\":{\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#primaryimage\",\"url\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg\",\"contentUrl\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg\",\"width\":1200,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#website\",\"url\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/\",\"name\":\"Blog | GPI NEWS\",\"description\":\"Guanajuato Puerto Interior\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#\/schema\/person\/f4851bb8a48c32d7fba5285caf4ef1c4\",\"name\":\"GPI NEWS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/612aca53a708cefc5ebe15ab0bc63c51a8ba58563e45c17848fa400e627e2717?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/612aca53a708cefc5ebe15ab0bc63c51a8ba58563e45c17848fa400e627e2717?s=96&d=mm&r=g\",\"caption\":\"GPI NEWS\"},\"url\":\"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/author\/rafa-jacinto\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre - Blog | GPI NEWS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/","og_locale":"es_MX","og_type":"article","og_title":"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre - Blog | GPI NEWS","og_description":"Durante los primeros 10 meses de 2023,\u00a0M\u00e9xico export\u00f3 2 millones 737,262 autos\u00a0al extranjero, lo que representa un incremento anual de 14.5%; de dicha cifra, el 77% de las unidades se enviaron a Estados Unidos, lo que se traduce en que el pa\u00eds vecino del norte lidera como\u00a0principal destino de exportaci\u00f3n\u00a0de veh\u00edculos. M\u00e9xico envi\u00f3 2 millones [&hellip;]","og_url":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/","og_site_name":"Blog | GPI NEWS","article_published_time":"2023-11-15T19:06:49+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg","type":"image\/jpeg"}],"author":"GPI NEWS","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"GPI NEWS","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/","url":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/","name":"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre - Blog | GPI NEWS","isPartOf":{"@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#primaryimage"},"image":{"@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#primaryimage"},"thumbnailUrl":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg","datePublished":"2023-11-15T19:06:49+00:00","author":{"@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#\/schema\/person\/f4851bb8a48c32d7fba5285caf4ef1c4"},"breadcrumb":{"@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#primaryimage","url":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg","contentUrl":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg","width":1200,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/2023\/11\/15\/estos-fueron-los-autos-mas-exportados-a-estados-unidos-de-enero-a-octubre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Estos fueron los autos m\u00e1s exportados a Estados Unidos de enero a octubre"}]},{"@type":"WebSite","@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#website","url":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/","name":"Blog | GPI NEWS","description":"Guanajuato Puerto Interior","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#\/schema\/person\/f4851bb8a48c32d7fba5285caf4ef1c4","name":"GPI NEWS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/612aca53a708cefc5ebe15ab0bc63c51a8ba58563e45c17848fa400e627e2717?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/612aca53a708cefc5ebe15ab0bc63c51a8ba58563e45c17848fa400e627e2717?s=96&d=mm&r=g","caption":"GPI NEWS"},"url":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/author\/rafa-jacinto\/"}]}},"jetpack_featured_media_url":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-content\/uploads\/2023\/11\/camionestas_.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcnMPA-1VC","_links":{"self":[{"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/posts\/7416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/comments?post=7416"}],"version-history":[{"count":1,"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/posts\/7416\/revisions"}],"predecessor-version":[{"id":7418,"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/posts\/7416\/revisions\/7418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/media\/7417"}],"wp:attachment":[{"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/media?parent=7416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/categories?post=7416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puertointerior.guanajuato.gob.mx\/blog\/wp-json\/wp\/v2\/tags?post=7416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}